{"id":5439,"date":"2019-05-13T13:11:36","date_gmt":"2019-05-13T11:11:36","guid":{"rendered":"https:\/\/pro-carro.be\/?p=5439"},"modified":"2019-02-20T06:12:51","modified_gmt":"2019-02-20T05:12:51","slug":"les-plus-et-les-moins-du-carrelage-en-travertin","status":"publish","type":"post","link":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/","title":{"rendered":"Les plus et les moins du carrelage en travertin"},"content":{"rendered":"<p>L\u2019aspect naturel et irr\u00e9gulier du carrelage en travertin s\u00e9duit de plus en plus de particuliers. Ce type de rev\u00eatement de mur et de sol en pierre naturelle permet en effet de donner du caract\u00e8re et de conf\u00e9rer une note de charme au sein de leur habitat. Convenant aussi bien \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur, le carrelage en travertin a pour principal avantage d\u2019\u00eatre plus abordable qu\u2019un rev\u00eatement en ardoise ou en marbre. D\u00e9couvrez ses points forts et ses points faibles.<\/p>\n<h2><strong>Le carrelage en travertin\u00a0: d\u00e9finition<\/strong><\/h2>\n<p>Il s\u2019agit d\u2019un rev\u00eatement de mur ou de sol en pierre naturelle. Le travertin est extrait d\u2019une roche calcaire s\u00e9dimentaire contenant essentiellement de l\u2019aragonite et de la calcite. Cette roche se retrouve le plus souvent \u00e0 proximit\u00e9 de sources d\u2019eau. Elle se forme \u00e0 la suite de la concentration de d\u00e9p\u00f4ts de calcaire au-dessus de la v\u00e9g\u00e9tation.<\/p>\n<p>Ce mat\u00e9riau, aussi appel\u00e9 \u00ab\u00a0tuf calcaire\u00a0\u00bb, est originaire de la Turquie et d\u2019Italie. Les irr\u00e9gularit\u00e9s de sa surface, qui est essaim\u00e9e de petites cavit\u00e9s, constituent sa particularit\u00e9. Pour faciliter l\u2019entretien du carrelage en travertin et le rendre doux au toucher, il suffit de reboucher ces trous avant la pose du rev\u00eatement.<\/p>\n<p>De couleur blanche \u00e0 l\u2019origine, le travertin peut afficher une teinte grise, beige, marron \u00e0 tendance rouge\u00e2tre ou jaun\u00e2tre en raison des impuret\u00e9s qui s\u2019incrustent dans la roche.<\/p>\n<p>Utilis\u00e9 depuis les temps antiques comme mat\u00e9riau de base pour la construction d\u2019habitats ou de murailles, le travertin est aujourd\u2019hui employ\u00e9 comme <a href=\"https:\/\/www.pro-carro.be\/a-chaque-style-de-deco-son-carrelage-mural\/\" target=\"_blank\" rel=\"noopener\">rev\u00eatement des murs<\/a> ou des sols pour habiller l\u2019int\u00e9rieur ou l\u2019ext\u00e9rieur d\u2019une maison. Cette pierre naturelle s\u2019adapte particuli\u00e8rement aux salles de bains modernes et aux all\u00e9es carrossables.<\/p>\n<h2><strong>Les \u00ab\u00a0plus\u00a0\u00bb du carrelage en travertin<\/strong><\/h2>\n<p>Sa forte capacit\u00e9 de r\u00e9sistance aux agressions exog\u00e8nes et sa solidit\u00e9 constituent les principaux atouts du carrelage en travertin. R\u00e9sistant notamment au gel, il convient parfaitement aux sols ext\u00e9rieurs. Naturellement antid\u00e9rapant, il s\u2019adapte aux pi\u00e8ces humides, telles que la salle de bains ou la cuisine.<\/p>\n<p>Ce type de rev\u00eatement se d\u00e9cline en un large \u00e9ventail de finitions. Il peut offrir un aspect vieilli pour apporter une touche d\u2019authenticit\u00e9 au sein d\u2019une pi\u00e8ce. Il peut \u00e9galement \u00eatre poli. Il affiche alors un aspect lisse qui met en valeur les dessins acquis par la pierre tout au long de sa formation. Si vous \u00eates adepte de la rusticit\u00e9,\u00a0 optez pour un carrelage \u00e0 l\u2019aspect bross\u00e9.<\/p>\n<p>Les travertins sont disponibles sous diff\u00e9rents formats. Vous avez ainsi la possibilit\u00e9 de jouer sur les formats pour personnaliser votre carrelage et obtenir un rev\u00eatement \u00e0 l\u2019aspect unique.<\/p>\n<p>En pierre naturelle, le carrelage en travertin permet d\u2019apporter du caract\u00e8re \u00e0 un habitat, une des raisons de son succ\u00e8s aupr\u00e8s des particuliers.<\/p>\n<p>Son co\u00fbt abordable constitue \u00e9galement un avantage non n\u00e9gligeable. Il est propos\u00e9 entre 30 et 60\u00a0\u20ac\/m\u00e8tre carr\u00e9, le prix variant en fonction de la qualit\u00e9, des finitions et de la provenance de la pierre. En tout cas, un carrelage en travertin revient nettement moins cher qu\u2019un rev\u00eatement en marbre, en granit ou en ardoise.<\/p>\n<h2><strong>Les \u00ab\u00a0moins\u00a0\u00bb du carrelage en travertin<\/strong><\/h2>\n<p>De par sa composition, le travertin est un mat\u00e9riau poreux. Il est ainsi difficile \u00e0 entretenir. Qu\u2019il soit utilis\u00e9 en rev\u00eatement de mur ou de sol, il ne supporte pas les produits m\u00e9nagers abrasifs. Afin de ne pas risquer de l\u2019endommager, son entretien doit \u00eatre r\u00e9alis\u00e9 avec un nettoyant doux \u00e0 base de savon noir ou de savon de Marseille.<\/p>\n<p>La pollution exerce un impact irr\u00e9versible sur le carrelage en travertin. Celui-ci a tendance \u00e0 noircir au fil du temps. Ce type de rev\u00eatement est \u00e9galement sensible aux taches et \u00e0 l\u2019humidit\u00e9. Pour \u00e9viter sa d\u00e9gradation pr\u00e9coce, pensez \u00e0 lui appliquer un traitement antitache et hydrofuge avant de le mettre en \u0153uvre.<\/p>\n<p>Le carrelage en travertin r\u00e9siste mal aux fum\u00e9es. Il ne convient donc pas \u00e0 un habitat citadin.<\/p>\n<p>La pose d\u2019un rev\u00eatement en pierre naturelle requiert le respect de certaines r\u00e8gles qui ne sont ma\u00eetris\u00e9es que par un carreleur sp\u00e9cialis\u00e9 qui facturera la pose, en moyenne, \u00e0 30\u00a0\u20ac\/m\u00e8tre carr\u00e9.<\/p>\n<h2><strong>Comment entretenir un carrelage en travertin\u00a0?<\/strong><\/h2>\n<p>Si vous souhaitez pr\u00e9server sur le long terme l\u2019aspect d\u2019origine de votre carrelage en travertin, vous devez appliquer une m\u00e9thode particuli\u00e8re pour son entretien.<\/p>\n<p>Le travertin se raye facilement. \u00c9vitez l\u2019emploi d\u2019\u00e9ponge abrasive et de produits m\u00e9nagers en poudre pour le nettoyer. Abstenez-vous \u00e9galement d\u2019utiliser des produits d\u00e9capants ou trop acides qui risquent de ronger la surface du rev\u00eatement en travertin.<\/p>\n<p>Comme cette pierre naturelle est poreuse, elle est facilement incrust\u00e9e par une tache. Celle-ci doit donc \u00eatre trait\u00e9e dans les meilleurs d\u00e9lais, autrement elle pourrait \u00eatre ind\u00e9l\u00e9bile.<\/p>\n<p>Pour entretenir au quotidien un carrelage en travertin, il suffit de le nettoyer avec une serpilli\u00e8re imbib\u00e9e d\u2019eau et de savon de Marseille ou de savon noir liquide. Au cas o\u00f9 le sol est tr\u00e8s sale, vous pouvez recourir \u00e0 un m\u00e9lange d\u2019eau chaude additionn\u00e9e d\u2019une faible quantit\u00e9 de cristaux de soude.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019aspect naturel et irr\u00e9gulier du carrelage en travertin s\u00e9duit de plus en plus de particuliers. Ce type de rev\u00eatement de mur et de sol en pierre naturelle permet en effet de donner du caract\u00e8re et de conf\u00e9rer une note de charme au sein de leur habitat. Convenant aussi bien \u00e0 l\u2019int\u00e9rieur qu\u2019\u00e0 l\u2019ext\u00e9rieur, le carrelage [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5440,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-5439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-trucs-astuces"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"KeyTech\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Procarro, portail du carrelage et des artisans carreleurs | D\u00e9couvrez des id\u00e9es de r\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\u00efques.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Les plus et les moins du carrelage en travertin\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-05-13T11:11:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-02-20T05:12:51+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Les plus et les moins du carrelage en travertin\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#article\",\"name\":\"Les plus et les moins du carrelage en travertin\",\"headline\":\"Les plus et les moins du carrelage en travertin\",\"author\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/author\\\/keytech\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/shutterstock_134455508-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Les plus et les moins du carrelage en travertin\"},\"datePublished\":\"2019-05-13T13:11:36+02:00\",\"dateModified\":\"2019-02-20T06:12:51+01:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#webpage\"},\"articleSection\":\"Trucs &amp; astuces, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/category\\\/trucs-astuces\\\/#listItem\",\"name\":\"Trucs &amp; astuces\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/category\\\/trucs-astuces\\\/#listItem\",\"position\":2,\"name\":\"Trucs &amp; astuces\",\"item\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/category\\\/trucs-astuces\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#listItem\",\"name\":\"Les plus et les moins du carrelage en travertin\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#listItem\",\"position\":3,\"name\":\"Les plus et les moins du carrelage en travertin\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/category\\\/trucs-astuces\\\/#listItem\",\"name\":\"Trucs &amp; astuces\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#organization\",\"name\":\"Procarro, portail du carrelage et des artisans carreleurs\",\"description\":\"D\\u00e9couvrez des id\\u00e9es de r\\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\\u00efques.\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/author\\\/keytech\\\/#author\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/author\\\/keytech\\\/\",\"name\":\"KeyTech\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/390ecf7fe7d404d245cd2f1c99bfcd5473b45beef7d30da954b42741c09c0fff?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"KeyTech\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#webpage\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/\",\"name\":\"Les plus et les moins du carrelage en travertin\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/author\\\/keytech\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/author\\\/keytech\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/shutterstock_134455508-1.jpg\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#mainImage\",\"width\":1920,\"height\":1080,\"caption\":\"Les plus et les moins du carrelage en travertin\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/les-plus-et-les-moins-du-carrelage-en-travertin\\\/#mainImage\"},\"datePublished\":\"2019-05-13T13:11:36+02:00\",\"dateModified\":\"2019-02-20T06:12:51+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/\",\"name\":\"Procarro, portail du carrelage et des artisans carreleurs\",\"description\":\"D\\u00e9couvrez des id\\u00e9es de r\\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\\u00efques.\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pro-carro.be\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Les plus et les moins du carrelage en travertin","description":"","canonical_url":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#article","name":"Les plus et les moins du carrelage en travertin","headline":"Les plus et les moins du carrelage en travertin","author":{"@id":"https:\/\/www.pro-carro.be\/fr\/author\/keytech\/#author"},"publisher":{"@id":"https:\/\/www.pro-carro.be\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.pro-carro.be\/wp-content\/uploads\/2019\/02\/shutterstock_134455508-1.jpg","width":1920,"height":1080,"caption":"Les plus et les moins du carrelage en travertin"},"datePublished":"2019-05-13T13:11:36+02:00","dateModified":"2019-02-20T06:12:51+01:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#webpage"},"isPartOf":{"@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#webpage"},"articleSection":"Trucs &amp; astuces, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/www.pro-carro.be\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/#listItem","name":"Trucs &amp; astuces"}},{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/#listItem","position":2,"name":"Trucs &amp; astuces","item":"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#listItem","name":"Les plus et les moins du carrelage en travertin"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#listItem","position":3,"name":"Les plus et les moins du carrelage en travertin","previousItem":{"@type":"ListItem","@id":"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/#listItem","name":"Trucs &amp; astuces"}}]},{"@type":"Organization","@id":"https:\/\/www.pro-carro.be\/fr\/#organization","name":"Procarro, portail du carrelage et des artisans carreleurs","description":"D\u00e9couvrez des id\u00e9es de r\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\u00efques.","url":"https:\/\/www.pro-carro.be\/fr\/"},{"@type":"Person","@id":"https:\/\/www.pro-carro.be\/fr\/author\/keytech\/#author","url":"https:\/\/www.pro-carro.be\/fr\/author\/keytech\/","name":"KeyTech","image":{"@type":"ImageObject","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/390ecf7fe7d404d245cd2f1c99bfcd5473b45beef7d30da954b42741c09c0fff?s=96&d=mm&r=g","width":96,"height":96,"caption":"KeyTech"}},{"@type":"WebPage","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#webpage","url":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/","name":"Les plus et les moins du carrelage en travertin","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.pro-carro.be\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#breadcrumblist"},"author":{"@id":"https:\/\/www.pro-carro.be\/fr\/author\/keytech\/#author"},"creator":{"@id":"https:\/\/www.pro-carro.be\/fr\/author\/keytech\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.pro-carro.be\/wp-content\/uploads\/2019\/02\/shutterstock_134455508-1.jpg","@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#mainImage","width":1920,"height":1080,"caption":"Les plus et les moins du carrelage en travertin"},"primaryImageOfPage":{"@id":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/#mainImage"},"datePublished":"2019-05-13T13:11:36+02:00","dateModified":"2019-02-20T06:12:51+01:00"},{"@type":"WebSite","@id":"https:\/\/www.pro-carro.be\/fr\/#website","url":"https:\/\/www.pro-carro.be\/fr\/","name":"Procarro, portail du carrelage et des artisans carreleurs","description":"D\u00e9couvrez des id\u00e9es de r\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\u00efques.","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.pro-carro.be\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Procarro, portail du carrelage et des artisans carreleurs | D\u00e9couvrez des id\u00e9es de r\u00e9alisations, des conseils professionnels et des informations pertinentes sur les carrelages et mosa\u00efques.","og:type":"article","og:title":"Les plus et les moins du carrelage en travertin","og:url":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/","article:published_time":"2019-05-13T11:11:36+00:00","article:modified_time":"2019-02-20T05:12:51+00:00","twitter:card":"summary","twitter:title":"Les plus et les moins du carrelage en travertin"},"aioseo_meta_data":{"post_id":"5439","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 02:05:18","updated":"2022-09-14 11:36:09","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.pro-carro.be\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/\" title=\"Trucs &amp; astuces\">Trucs &amp; astuces<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLes plus et les moins du carrelage en travertin\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.pro-carro.be\/fr\/"},{"label":"Trucs &amp; astuces","link":"https:\/\/www.pro-carro.be\/fr\/category\/trucs-astuces\/"},{"label":"Les plus et les moins du carrelage en travertin","link":"https:\/\/www.pro-carro.be\/fr\/les-plus-et-les-moins-du-carrelage-en-travertin\/"}],"_links":{"self":[{"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/posts\/5439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/comments?post=5439"}],"version-history":[{"count":0,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/posts\/5439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/media\/5440"}],"wp:attachment":[{"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/media?parent=5439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/categories?post=5439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pro-carro.be\/fr\/wp-json\/wp\/v2\/tags?post=5439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}